{"id":9815,"date":"2024-10-30T20:45:55","date_gmt":"2024-10-30T20:45:55","guid":{"rendered":"https:\/\/ellascomunicacion.com\/en-marcha-el-rodaje-de-la-serie-el-centro"},"modified":"2024-12-16T07:58:50","modified_gmt":"2024-12-16T07:58:50","slug":"en-marcha-el-rodaje-de-la-serie-el-centro","status":"publish","type":"post","link":"https:\/\/ellascomunicacion.com\/en\/en-marcha-el-rodaje-de-la-serie-el-centro\/","title":{"rendered":"En marcha el rodaje de la serie \u201cEl Centro\u201d"},"content":{"rendered":"<p>Foto: Niete<\/p>\n<p><strong>El Centro<\/strong>, la nueva serie original Movistar Plus+ en colaboraci\u00f3n con Fonte Films, arranca su rodaje en Madrid y llegar\u00e1 a la plataforma en 2025.<\/p>\n<p>La serie, creada por David Moreno, dirigida por David Ulloa y con guion de David Moreno, Ra\u00fal L\u00f3pez y Eva Saiz, es un thriller de espionaje actual y realista que explora los retos personales y profesionales a los que se enfrentan un grupo de Oficiales de Inteligencia del CNI en un mundo convulso que nos recuerda a los tiempos de la Guerra Fr\u00eda.<\/p>\n<p>David Ulloa, director: &#8220;<em>Siendo &#8216;EL CENTRO&#8217; una serie de esp\u00edas, el reto estaba en no quedarnos solo ah\u00ed y darle una peque\u00f1a vuelta de tuerca al asunto, profundizando todo lo que pudi\u00e9semos en cada uno de nuestros personajes. En eso los directores no somos muy distintos de esos esp\u00edas. Vampiros emocionales que se cuelan en la intimidad de la gente y observan sin ser vistos. Gracias a eso entenderemos el compromiso de nuestro protagonista, Michelin, por una causa superior a pesar de todo el sacrificio que conlleva. \u00bfC\u00f3mo hace para mantener ese delicado equilibrio entre su vocaci\u00f3n como miembro del CNI y su estabilidad familiar? \u00bfC\u00f3mo consigue no perder la cordura ante este mundo de medias verdades, desconfianzas y algunas veces traiciones? Dirigiremos desde las sombras, con la cobertura bien preparada y esperando que no noten nuestra presencia<\/em>&#8220;.<\/p>\n<p>El rodaje de <strong>El Centro<\/strong> est\u00e1 previsto que termine en febrero y su estreno llegar\u00e1 a lo largo de 2025.<\/p>\n<p>Ambientada en la actualidad, pero con ecos de la Guerra Fr\u00eda, <strong>El Centro<\/strong> es un thriller de espionaje que se adentra en el desconocido universo del Centro Nacional de Inteligencia (CNI). La trama arranca con un asesinato que destapa una operaci\u00f3n internacional y lleva a los protagonistas a una carrera contrarreloj para descubrir a un traidor en sus filas, mientras intentan desmantelar una conspiraci\u00f3n liderada por el enigm\u00e1tico agente ruso Volkov.<\/p>\n<p>La serie es una mirada \u00edntima y coral a los desaf\u00edos que enfrentan los oficiales de inteligencia, mientras navegan entre el deber, la lealtad y la traici\u00f3n.<\/p>\n<p><strong>El Centro<\/strong> cuenta con un reparto coral encabezado por Juan Diego Botto (&#8216;Todos mienten&#8217;), Elena Mart\u00edn (&#8216;Creatura&#8217;), Israel Elejalde (&#8216;Las noches de Tef\u00eda&#8217;), Elisabet Casanovas (&#8216;La ruta&#8217;), Clara Segura (&#8216;El 47&#8217;), Trist\u00e1n Ulloa (&#8216;El caso Asunta&#8217;), David Lorente (&#8216;Buscando a Coque&#8217;) y Nacho S\u00e1nchez (&#8216;Mant\u00edcora&#8217;).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Niete El Centro, la nueva serie original Movistar Plus+ en colaboraci\u00f3n con Fonte Films, arranca su rodaje en Madrid y llegar\u00e1 a la plataforma en 2025. La serie, creada por David Moreno, dirigida por David Ulloa y con guion de David Moreno, Ra\u00fal L\u00f3pez y Eva Saiz, es un thriller de espionaje actual y realista que explora los retos personales y profesionales a los que se enfrentan un grupo de Oficiales de Inteligencia del CNI en un mundo convulso que nos recuerda a los tiempos de la Guerra Fr\u00eda. David Ulloa, director: &#8220;Siendo &#8216;EL CENTRO&#8217; una serie de esp\u00edas, el reto estaba en no quedarnos solo ah\u00ed y darle una peque\u00f1a vuelta de tuerca al asunto, profundizando todo lo que pudi\u00e9semos en cada uno de nuestros personajes. En eso los directores no somos muy distintos de esos esp\u00edas. Vampiros emocionales que se cuelan en la intimidad de la gente<\/p>\n","protected":false},"author":2,"featured_media":9813,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70,64],"tags":[],"class_list":["post-9815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-en","category-news"],"_links":{"self":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/9815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/comments?post=9815"}],"version-history":[{"count":1,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/9815\/revisions"}],"predecessor-version":[{"id":9816,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/9815\/revisions\/9816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media\/9813"}],"wp:attachment":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media?parent=9815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/categories?post=9815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/tags?post=9815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}