{"id":7942,"date":"2024-03-19T14:27:45","date_gmt":"2024-03-19T14:27:45","guid":{"rendered":"https:\/\/ellascomunicacion.com\/marbella-la-nueva-serie-de-movistar-plus-creada-por-dani-de-la-torre-y-alberto-marini-se-estrena-el-2-de-mayo"},"modified":"2024-03-19T14:28:20","modified_gmt":"2024-03-19T14:28:20","slug":"marbella-la-nueva-serie-de-movistar-plus-creada-por-dani-de-la-torre-y-alberto-marini-se-estrena-el-2-de-mayo","status":"publish","type":"post","link":"https:\/\/ellascomunicacion.com\/en\/marbella-la-nueva-serie-de-movistar-plus-creada-por-dani-de-la-torre-y-alberto-marini-se-estrena-el-2-de-mayo\/","title":{"rendered":"&#8220;Marbella&#8221; la nueva serie de Movistar Plus+ creada por Dani De la Torre y Alberto Marini se estrena el 2 de mayo"},"content":{"rendered":"<p>Foto: \u00a9 Mar\u00eda Heras<\/p>\n<p><strong>Marbella<\/strong>, la nueva serie Movistar Plus+ producida por Buend\u00eda Estudios Canarias que se estrenar\u00e1 el 2 de mayo, es un thriller de seis episodios que cuenta con una trama trepidante en la que ficci\u00f3n e<br \/>\ninvestigaci\u00f3n period\u00edstica se dan la mano.<\/p>\n<p>Hugo Silva se pone en la piel de C\u00e9sar, un ambicioso y seductor abogado que est\u00e1 dispuesto a retorcer la ley y saltarse cualquier c\u00f3digo \u00e9tico o moral para lograr sus objetivos y convertirse en el abogado m\u00e1s cotizado de Marbella.<br \/>\nEl reparto principal lo completan Ana Isabelle, Khalid El Paisano, Aurora Moroni, Elvira M\u00ednguez, Manuela Calle, Mohamed Said, Daniele Fileti y Fernando Cayo.<\/p>\n<p>Tras el \u00e9xito de &#8220;La Unidad&#8221; (Mejor Ficci\u00f3n y Mejor Direcci\u00f3n en los Premios Iris 2022) y &#8220;La Unidad Kabul&#8221; (Mejor Ficci\u00f3n, Mejor Guion de Ficci\u00f3n, Mejor Fotograf\u00eda y Mejor Producci\u00f3n en los Premios Iris 2023), Dani de la Torre y Alberto Marini se ponen al frente de esta nueva producci\u00f3n, una idea original de los periodistas Nacho Carretero (&#8220;En el corredor de la muerte&#8221;, &#8220;Fari\u00f1a&#8221;) y Arturo Lezcano (podcast &#8220;En el corredor de la muerte&#8221;), grandes conocedores del submundo de la delincuencia con ramificaciones en todo el planeta que operan en la Costa del Sol. Adem\u00e1s, Alberto Marini firma el guion de la serie.<br \/>\nLa serie tiene como punto de partida el reportaje que public\u00f3 en 2021 el diario El Pa\u00eds: Marbella, sede global del crimen organizado, que hac\u00eda un exhaustivo an\u00e1lisis sobre las bandas que operan en la costa marbell\u00ed.<\/p>\n<p>Sinopsis<br \/>\nC\u00e9sar es un abogado de \u00e9xito afincado en Marbella, la capital mundial de la mafia. Guapo, rico, hedonista, ego\u00edsta, ambicioso&#8230; sabe que para mantener su estatus tiene que ser el mejor en los tribunales y el hombre que todos conozcan en las salvajes fiestas marbell\u00edes, donde hacen negocios los numerosos grupos criminales que operan en la Costa del Sol.<br \/>\nC\u00e9sar tiene muy claro que, para no tener problemas en la vida, hay que ser amigo de todos y no cruzar nunca ciertas l\u00edneas. Pero cuando menos se lo espera, descubre que est\u00e1 en ojo del hurac\u00e1n y qui\u00e9n necesita a un abogado que le salve es precisamente \u00e9l.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: \u00a9 Mar\u00eda Heras Marbella, la nueva serie Movistar Plus+ producida por Buend\u00eda Estudios Canarias que se estrenar\u00e1 el 2 de mayo, es un thriller de seis episodios que cuenta con una trama trepidante en la que ficci\u00f3n e investigaci\u00f3n period\u00edstica se dan la mano. Hugo Silva se pone en la piel de C\u00e9sar, un ambicioso y seductor abogado que est\u00e1 dispuesto a retorcer la ley y saltarse cualquier c\u00f3digo \u00e9tico o moral para lograr sus objetivos y convertirse en el abogado m\u00e1s cotizado de Marbella. El reparto principal lo completan Ana Isabelle, Khalid El Paisano, Aurora Moroni, Elvira M\u00ednguez, Manuela Calle, Mohamed Said, Daniele Fileti y Fernando Cayo. Tras el \u00e9xito de &#8220;La Unidad&#8221; (Mejor Ficci\u00f3n y Mejor Direcci\u00f3n en los Premios Iris 2022) y &#8220;La Unidad Kabul&#8221; (Mejor Ficci\u00f3n, Mejor Guion de Ficci\u00f3n, Mejor Fotograf\u00eda y Mejor Producci\u00f3n en los Premios Iris 2023), Dani de la Torre y<\/p>\n","protected":false},"author":2,"featured_media":7940,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[70,64],"tags":[],"class_list":["post-7942","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-blog-en","category-news","post_format-post-format-video"],"_links":{"self":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/7942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/comments?post=7942"}],"version-history":[{"count":1,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/7942\/revisions"}],"predecessor-version":[{"id":7943,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/7942\/revisions\/7943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media\/7940"}],"wp:attachment":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media?parent=7942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/categories?post=7942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/tags?post=7942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}