{"id":7691,"date":"2023-06-19T11:07:49","date_gmt":"2023-06-19T11:07:49","guid":{"rendered":"https:\/\/ellascomunicacion.com\/todos-mienten-la-serie-original-movistar-plus-creada-y-dirigida-por-pau-freixas-finaliza-el-rodaje-de-su-segunda-temporada"},"modified":"2023-06-19T11:11:54","modified_gmt":"2023-06-19T11:11:54","slug":"todos-mienten-la-serie-original-movistar-plus-creada-y-dirigida-por-pau-freixas-finaliza-el-rodaje-de-su-segunda-temporada","status":"publish","type":"post","link":"https:\/\/ellascomunicacion.com\/en\/todos-mienten-la-serie-original-movistar-plus-creada-y-dirigida-por-pau-freixas-finaliza-el-rodaje-de-su-segunda-temporada\/","title":{"rendered":"&#8220;Todos mienten&#8221;, la serie original Movistar Plus+ creada y dirigida por Pau Freixas, finaliza el rodaje de su segunda temporada"},"content":{"rendered":"<p>Foto: \u00a9 Daniel Escal\u00e9<\/p>\n<p><strong>Todos mienten<\/strong>, la serie original Movistar Plus+ en colaboraci\u00f3n con Filmax y creada y dirigida por Pau Freixas, ha finalizado el rodaje de su segunda temporada que se ha desarrollado durante 12 semanas en 26 localizaciones naturales repartidas en 20 municipios de la Provincia de Barcelona y la Costa Brava, desde el Pre-pirineo catal\u00e1n hasta el sur de Barcelona.<\/p>\n<p>Para crear el universo Belmonte, en el rodaje han intervenido 165 t\u00e9cnicos, 34 actores, 711 figurantes y 14 especialistas, todos en una sola unidad de rodaje y bajo la direcci\u00f3n \u00fanica de Pau Freixas. <\/p>\n<p><strong>Todos mienten<\/strong> es un puzle a resolver con mentiras, secretos, alianzas y crisis matrimoniales y vitales. El suspense, el drama, el humor negro y los personajes imprevisibles e impulsivos vuelven a ser los ingredientes fundamentales de la segunda temporada.<\/p>\n<p>La T2 de <strong>Todos mienten<\/strong> vuelve a reunir a un elenco de actrices y actores de primer nivel: Irene Arcos, Natalia Verbeke, Eva Santolaria, Leonardo Sbaraglia, Juan Diego Botto, Ernesto Alterio, Miren Ibarguren, Jorge Bosch, Carmen Arrufat, Berta Casta\u00f1\u00e9, Lu Colomina, Amaia Salamanca y Marc Balaguer. Como novedad, Alberto San Juan y Kiti M\u00e1nver se han incorporado al reparto en los papeles de Beto y \u00c1ngela respectivamente. <\/p>\n<p>Sinopsis <\/p>\n<p>Belmonte trata de recuperarse del reciente asesinato de Iv\u00e1n. Su presunto autor, N\u00e9stor, ha huido y a la gente de la comunidad le falta tiempo para encender sus barbacoas y pasar p\u00e1gina. Macarena y Ana silencian el secreto que las une, mataron y se deshicieron del cad\u00e1ver de N\u00e9stor tir\u00e1ndolo por una cantera. Est\u00e1n convencidas de que todo est\u00e1 bajo control, todo va a salir bien, es cuesti\u00f3n de que pase algo de tiempo y que se olvide el tema. Pero no contaban con que la polic\u00eda encontrase un cuerpo en una caba\u00f1a abandonada. Est\u00e1 descompuesto con cal y es irreconocible. Pero lleva puesto el anillo de N\u00e9stor y todo apunta que es \u00e9l. \u00bfC\u00f3mo puede ser? Si Macarena y Ana lo tiraron por esa cantera, \u00bfqu\u00e9 hace en ese lugar? \u00bfY si no es N\u00e9stor, qui\u00e9n es ese cad\u00e1ver? Tienen que descubrir que est\u00e1 pasando antes de que las descubran a ellas. Alguien miente. \u00bfO quiz\u00e1 lo hacen todos?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: \u00a9 Daniel Escal\u00e9 Todos mienten, la serie original Movistar Plus+ en colaboraci\u00f3n con Filmax y creada y dirigida por Pau Freixas, ha finalizado el rodaje de su segunda temporada que se ha desarrollado durante 12 semanas en 26 localizaciones naturales repartidas en 20 municipios de la Provincia de Barcelona y la Costa Brava, desde el Pre-pirineo catal\u00e1n hasta el sur de Barcelona. Para crear el universo Belmonte, en el rodaje han intervenido 165 t\u00e9cnicos, 34 actores, 711 figurantes y 14 especialistas, todos en una sola unidad de rodaje y bajo la direcci\u00f3n \u00fanica de Pau Freixas. Todos mienten es un puzle a resolver con mentiras, secretos, alianzas y crisis matrimoniales y vitales. El suspense, el drama, el humor negro y los personajes imprevisibles e impulsivos vuelven a ser los ingredientes fundamentales de la segunda temporada. La T2 de Todos mienten vuelve a reunir a un elenco de actrices y<\/p>\n","protected":false},"author":2,"featured_media":7689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70,64],"tags":[],"class_list":["post-7691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-en","category-news"],"_links":{"self":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/7691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/comments?post=7691"}],"version-history":[{"count":1,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/7691\/revisions"}],"predecessor-version":[{"id":7692,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/7691\/revisions\/7692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media\/7689"}],"wp:attachment":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media?parent=7691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/categories?post=7691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/tags?post=7691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}