{"id":6473,"date":"2020-06-23T12:55:01","date_gmt":"2020-06-23T12:55:01","guid":{"rendered":"http:\/\/ellascomunicacion.com\/en\/teaser-trailer-de-antidisturbios-una-serie-original-movistar-dirigida-por-rodrigo-sorogoyen"},"modified":"2020-06-23T12:55:53","modified_gmt":"2020-06-23T12:55:53","slug":"teaser-trailer-de-antidisturbios-una-serie-original-movistar-dirigida-por-rodrigo-sorogoyen","status":"publish","type":"post","link":"https:\/\/ellascomunicacion.com\/en\/teaser-trailer-de-antidisturbios-una-serie-original-movistar-dirigida-por-rodrigo-sorogoyen\/","title":{"rendered":"Teaser tr\u00e1iler de &#8220;Antidisturbios&#8221;, una serie original Movistar+ dirigida por Rodrigo Sorogoyen"},"content":{"rendered":"<p>Foto: \u00a9 Jos\u00e9 Haro<\/p>\n<p>Creada por Rodrigo Sorogoyen e Isabel Pe\u00f1a, <em>Antidisturbios<\/em> es una serie policiaca en\u00e9rgica, un relato contempor\u00e1neo que combina la acci\u00f3n vibrante con la construcci\u00f3n del retrato humano de sus protagonistas. El thriller, ficci\u00f3n original de Movistar+ en colaboraci\u00f3n con The Lab y Caballo Films, constar\u00e1 de 6 episodios de 50 minutos de duraci\u00f3n y se estrenar\u00e1 en Movistar+ despu\u00e9s del verano.<\/p>\n<p>Con una mirada en crudo y un ritmo vertiginoso, el nominado al Oscar\u00ae Rodrigo Sorogoyen, cocreador, coguionista y director de la serie, y uno de los autores m\u00e1s premiados del cine espa\u00f1ol, dirige un relato que gira en torno a la figura del polic\u00eda antidisturbios en nuestra sociedad.<\/p>\n<p>En palabras de su director se trata de \u201cuna serie pegada a la realidad y a la \u00e9poca en la que vivimos, pero no juzga, no alimenta estereotipos, no caricaturiza ning\u00fan colectivo ni se posiciona pol\u00edticamente\u201d. <\/p>\n<p>Vicky Luengo interpreta a una agente de Asuntos Internos que investiga a los seis polic\u00edas antidisturbios del \u201cPuma 93\u201d, un personaje poli\u00e9drico que completa el juego entre perseguidora y perseguidos en un entorno hostil. Con una complicidad que traspasa la pantalla, Ra\u00fal Ar\u00e9valo, \u00c1lex Garc\u00eda, Hovik Keuchkerian, Roberto \u00c1lamo, Ra\u00fal Prieto y Patrick Criado dan vida al grupo de polic\u00edas investigados para los que componen unos personajes complejos y contradictorios. <\/p>\n<p>Escrita por Eduardo Villanueva, Isabel Pe\u00f1a y el propio Sorogoyen, la apuesta trepidante del guion se traduce en pantalla en una producci\u00f3n rodada en m\u00e1s de 100 localizaciones naturales, m\u00e1s de 200 sets, un furg\u00f3n policial protagonista (acondicionado) y cientos de figurantes. Se ha rodado en las localizaciones naturales que han inspirado la trama como comisarias de polic\u00eda, una corrala madrile\u00f1a, casas, bares, juzgados o una playa. La b\u00fasqueda del ambiente realista de calles, t\u00faneles, barrios, despachos o pasillos ha construido un paisaje dram\u00e1tico inmersivo para los espectadores.<\/p>\n<p>Rodeado de su equipo t\u00e9cnico habitual, Sorogoyen propone una puesta en escena hiperrealista que se extiende al dise\u00f1o de personajes, tramas y al trabajo t\u00e9cnico detr\u00e1s de las c\u00e1maras y que ha supuesto grandes retos en todos los departamentos: desde la m\u00fasica de Olivier Arson, pasando por el vestuario de Alberto Valc\u00e1rcel, el sonido de Aitor Berenguer, el montaje de Alberto del Campo, hasta la fotograf\u00eda de Alex de Pablo. <\/p>\n<p>SINOPSIS<br \/>\nSeis antidisturbios ejecutan un desahucio en el centro de Madrid que se complica y un hombre acaba muriendo. Un equipo de Asuntos Internos ser\u00e1 el encargado de investigar los hechos y los seis antidisturbios se enfrentan a una acusaci\u00f3n de homicidio imprudente. El grupo de agentes busca una salida por su cuenta que acaba separ\u00e1ndolos y, finalmente, complicando a\u00fan m\u00e1s la situaci\u00f3n. Laia, una de las agentes de Asuntos Internos, se obsesiona con el caso y acaba descubriendo que, tras ese desahucio malogrado, hay mucho m\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: \u00a9 Jos\u00e9 Haro Creada por Rodrigo Sorogoyen e Isabel Pe\u00f1a, Antidisturbios es una serie policiaca en\u00e9rgica, un relato contempor\u00e1neo que combina la acci\u00f3n vibrante con la construcci\u00f3n del retrato humano de sus protagonistas. El thriller, ficci\u00f3n original de Movistar+ en colaboraci\u00f3n con The Lab y Caballo Films, constar\u00e1 de 6 episodios de 50 minutos de duraci\u00f3n y se estrenar\u00e1 en Movistar+ despu\u00e9s del verano. Con una mirada en crudo y un ritmo vertiginoso, el nominado al Oscar\u00ae Rodrigo Sorogoyen, cocreador, coguionista y director de la serie, y uno de los autores m\u00e1s premiados del cine espa\u00f1ol, dirige un relato que gira en torno a la figura del polic\u00eda antidisturbios en nuestra sociedad. En palabras de su director se trata de \u201cuna serie pegada a la realidad y a la \u00e9poca en la que vivimos, pero no juzga, no alimenta estereotipos, no caricaturiza ning\u00fan colectivo ni se posiciona pol\u00edticamente\u201d. Vicky<\/p>\n","protected":false},"author":2,"featured_media":6471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[64],"tags":[],"class_list":["post-6473","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-news","post_format-post-format-video"],"_links":{"self":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/6473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/comments?post=6473"}],"version-history":[{"count":1,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/6473\/revisions"}],"predecessor-version":[{"id":6474,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/6473\/revisions\/6474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media\/6471"}],"wp:attachment":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media?parent=6473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/categories?post=6473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/tags?post=6473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}