{"id":6426,"date":"2020-02-26T15:44:13","date_gmt":"2020-02-26T15:44:13","guid":{"rendered":"http:\/\/ellascomunicacion.com\/en\/11-de-septiembre-estreno-en-salas-de-malnazidos-de-javier-ruiz-caldera-y-alberto-de-toro"},"modified":"2020-03-02T15:49:55","modified_gmt":"2020-03-02T15:49:55","slug":"11-de-septiembre-estreno-en-salas-de-malnazidos-de-javier-ruiz-caldera-y-alberto-de-toro","status":"publish","type":"post","link":"https:\/\/ellascomunicacion.com\/en\/11-de-septiembre-estreno-en-salas-de-malnazidos-de-javier-ruiz-caldera-y-alberto-de-toro\/","title":{"rendered":"11 de septiembre, estreno en salas de &#8220;Malnazidos&#8221; de Javier Ruiz Caldera y Alberto de Toro"},"content":{"rendered":"<p>Foto: \u00a9 Quim Vives<\/p>\n<p>El pr\u00f3ximo onze de septiembre se estrenar\u00e1 en cines <em>Malnazidos<\/em>, una pel\u00edcula de acci\u00f3n y aventuras en la que un grupo de combatientes huidos de bandos rivales durante la Guerra Civil deben aliarse para hacer frente a un adversario com\u00fan\u2026 \u00a1zombies! Para lograrlo, tendr\u00e1n que dejar de lado el odio mutuo y as\u00ed evitar convertirse en uno de ellos.<\/p>\n<p>Codirigida por Javier Ruiz Caldera y Alberto de Toro y escrita por Jaime Marques Olarreaga y Cristian Conti a partir de la novela Noche de Difuntos del 38 de Manuel Mart\u00edn Ferreras, la pel\u00edcula cuenta con un reparto coral encabezado por Miki Esparb\u00e9, Aura Garrido, Luis Callejo, \u00c1lvaro Cervantes, Jes\u00fas Carroza y Mar\u00eda Botto.<\/p>\n<p><em>Malnazidos<\/em> es una producci\u00f3n de TELECINCO CINEMA, CACTUS FLOWER PRODUCCIONES, MALNAZIDOS AIE, LA TERRAZA FILMS e IKIRU FILMS, con la participaci\u00f3n de MEDIASET ESPA\u00d1A y MEDITERR\u00c1NEO MEDIASET GROUP, y ser\u00e1 distribuida en Espa\u00f1a por SONY PICTURES ENTERTAINMENT IBERIA.<\/p>\n<p>SINOPSIS<br \/>\nMeses de sangrientos combates han dejado tras de s\u00ed miles de muertos en las trincheras. Jan Lozano, capit\u00e1n de la quinta brigada, cae prisionero. La \u00fanica posibilidad de escapar a la sentencia de muerte es hacer frente a una misi\u00f3n imposible en campo enemigo. Pero un peligro mayor del esperado obligar\u00e1 a los bandos rivales a unirse contra un nuevo y desconocido adversario. Tendr\u00e1n que dejar de lado el odio mutuo y as\u00ed evitar convertirse en zombis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: \u00a9 Quim Vives El pr\u00f3ximo onze de septiembre se estrenar\u00e1 en cines Malnazidos, una pel\u00edcula de acci\u00f3n y aventuras en la que un grupo de combatientes huidos de bandos rivales durante la Guerra Civil deben aliarse para hacer frente a un adversario com\u00fan\u2026 \u00a1zombies! Para lograrlo, tendr\u00e1n que dejar de lado el odio mutuo y as\u00ed evitar convertirse en uno de ellos. Codirigida por Javier Ruiz Caldera y Alberto de Toro y escrita por Jaime Marques Olarreaga y Cristian Conti a partir de la novela Noche de Difuntos del 38 de Manuel Mart\u00edn Ferreras, la pel\u00edcula cuenta con un reparto coral encabezado por Miki Esparb\u00e9, Aura Garrido, Luis Callejo, \u00c1lvaro Cervantes, Jes\u00fas Carroza y Mar\u00eda Botto. Malnazidos es una producci\u00f3n de TELECINCO CINEMA, CACTUS FLOWER PRODUCCIONES, MALNAZIDOS AIE, LA TERRAZA FILMS e IKIRU FILMS, con la participaci\u00f3n de MEDIASET ESPA\u00d1A y MEDITERR\u00c1NEO MEDIASET GROUP, y ser\u00e1 distribuida en Espa\u00f1a<\/p>\n","protected":false},"author":2,"featured_media":6424,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[],"class_list":["post-6426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/6426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/comments?post=6426"}],"version-history":[{"count":1,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/6426\/revisions"}],"predecessor-version":[{"id":6427,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/6426\/revisions\/6427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media\/6424"}],"wp:attachment":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media?parent=6426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/categories?post=6426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/tags?post=6426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}