{"id":5872,"date":"2018-09-25T08:41:15","date_gmt":"2018-09-25T08:41:15","guid":{"rendered":"http:\/\/ellascomunicacion.com\/en\/la-noche-de-12-anos-representara-a-uruguay-en-los-oscar-y-en-los-premios-goya"},"modified":"2018-09-25T08:43:07","modified_gmt":"2018-09-25T08:43:07","slug":"la-noche-de-12-anos-representara-a-uruguay-en-los-oscar-y-en-los-premios-goya","status":"publish","type":"post","link":"https:\/\/ellascomunicacion.com\/en\/la-noche-de-12-anos-representara-a-uruguay-en-los-oscar-y-en-los-premios-goya\/","title":{"rendered":"\u201cLa noche de 12 a\u00f1os\u201d representar\u00e1 a Uruguay en los Oscar y en los Premios Goya"},"content":{"rendered":"<p>Foto: Tornasol<\/p>\n<p>La pel\u00edcula <em>La noche de 12 a\u00f1os<\/em>, escrita y dirigida por Alvaro Brechner, ha sido un\u00e1nimemente elegida por los acad\u00e9micos de su pa\u00eds para representar a Uruguay en la 91\u00aa edici\u00f3n de los Premios Oscar y tambi\u00e9n en los premios Goya en su 33\u00aa edici\u00f3n.<br \/>\nDespu\u00e9s de su ovacionada presentaci\u00f3n en el marco del prestigioso Festival Internacional de Cine de Venecia, world premiere de la pel\u00edcula, y la emotiva recepci\u00f3n en el Festival Internacional de Cine de San Sebasti\u00e1n, donde compite en la Secci\u00f3n Horizontes, <em>La noche de 12 a\u00f1os<\/em> ha sido tambi\u00e9n la encargada de abrir el Festival de Biarritz Amerique Latine, que este a\u00f1o adem\u00e1s pone su foco en Uruguay y su cinematograf\u00eda.<\/p>\n<p>El filme, que llegar\u00e1 a los cines de Espa\u00f1a el 23 de noviembre, est\u00e1 protagonizado por Antonio de la Torre, Chino Dar\u00edn y Alfonso Tort. El reparto lo completan Soledad Villamil y Silvia P\u00e9rez Cruz.<\/p>\n<p>Inspirada en la historia real de Jos\u00e9 Mujica, Mauricio Rosencof y Eleuterio Fern\u00e1ndez Huidobro, <em>La noche de 12 a\u00f1os<\/em> es una historia de superaci\u00f3n y resistencia, pero, sobre todo, es la historia de la lucha existencial de tres hombres que en sus horas m\u00e1s oscuras se aferraron a su esp\u00edritu para mantener su humanidad y esperanza.<\/p>\n<p>Producida por TORNASOL y ALCARAVAN AIE (Espa\u00f1a) en coproducci\u00f3n con HADDOCK FILMS-ALEPH MEDIA (Argentina), MANNY FILMS (Francia) y SALADO(Uruguay), con la participaci\u00f3n de MOVISTAR+, NETFLIX y ZDF\/ARTE, y el apoyo del ICAA, INCAA, CNC, L\u00b4AIDE AUX CINEMAS DU MONDE, INSTITUT FRAN\u00c7AIS, IBERMEDIA y EURIMAGES, la pel\u00edcula ser\u00e1 distribuida en Espa\u00f1a por SYLDAVIA.<\/p>\n<p>La prensa ha dicho de ella:<br \/>\n\u201cUna lecci\u00f3n de vida, que sin dudas se convertir\u00e1 en un hito del cine latinoamericano contempor\u00e1neo.\u201d<br \/>\nMacguffin<\/p>\n<p>\u201cSorprendente y cautivante, el director usa el humor y la poes\u00eda para ilustrar la lucha en la oscuridad. Una maravillosa historia visual sobre la persistencia y resistencia humana.\u201d<br \/>\nDMovies<\/p>\n<p>\u201cEs imposible no conmoverse con las historias de vida y lucha de estos tres hombres que marcaron la historia\u201d<br \/>\nOtros cines (Diego Batlle-Argentina)<\/p>\n<p>\u201cUna exploraci\u00f3n sobre la condici\u00f3n humana.\u201d<br \/>\nVariety<\/p>\n<p>Sinopsis<br \/>\nTres hombres son sometidos a un secreto experimento a trav\u00e9s del cual la dictadura militar quiere volverlos locos. Arrojados a diminutos calabozos, no pueden hablar, apenas ver, comer o dormir. Empujados sus cuerpos y mentes m\u00e1s all\u00e1 de los l\u00edmites de lo imaginable, los rehenes libraron una batalla existencial para escapar a la terrible realidad que los condenaba a la locura. La pel\u00edcula est\u00e1 basada en los 12 a\u00f1os de confinamiento solitario que vivieron tres de las personalidades m\u00e1s reconocidas del Uruguay contempor\u00e1neo, entre ellos su expresidente, Jos\u00e9 \u201cPepe\u201d Mujica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Tornasol La pel\u00edcula La noche de 12 a\u00f1os, escrita y dirigida por Alvaro Brechner, ha sido un\u00e1nimemente elegida por los acad\u00e9micos de su pa\u00eds para representar a Uruguay en la 91\u00aa edici\u00f3n de los Premios Oscar y tambi\u00e9n en los premios Goya en su 33\u00aa edici\u00f3n. Despu\u00e9s de su ovacionada presentaci\u00f3n en el marco del prestigioso Festival Internacional de Cine de Venecia, world premiere de la pel\u00edcula, y la emotiva recepci\u00f3n en el Festival Internacional de Cine de San Sebasti\u00e1n, donde compite en la Secci\u00f3n Horizontes, La noche de 12 a\u00f1os ha sido tambi\u00e9n la encargada de abrir el Festival de Biarritz Amerique Latine, que este a\u00f1o adem\u00e1s pone su foco en Uruguay y su cinematograf\u00eda. El filme, que llegar\u00e1 a los cines de Espa\u00f1a el 23 de noviembre, est\u00e1 protagonizado por Antonio de la Torre, Chino Dar\u00edn y Alfonso Tort. El reparto lo completan Soledad Villamil y Silvia<\/p>\n","protected":false},"author":2,"featured_media":5870,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[],"class_list":["post-5872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/comments?post=5872"}],"version-history":[{"count":1,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5872\/revisions"}],"predecessor-version":[{"id":5873,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5872\/revisions\/5873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media\/5870"}],"wp:attachment":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media?parent=5872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/categories?post=5872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/tags?post=5872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}