{"id":5847,"date":"2018-08-03T10:45:06","date_gmt":"2018-08-03T10:45:06","guid":{"rendered":"http:\/\/ellascomunicacion.com\/en\/arde-madrid-la-serie-original-de-movistar-creada-por-paco-leon-y-anna-r-costa-tendra-su-premiere-mundial-en-el-festival-internacional-de-cine-de-san-sebastian"},"modified":"2018-08-03T10:47:30","modified_gmt":"2018-08-03T10:47:30","slug":"arde-madrid-la-serie-original-de-movistar-creada-por-paco-leon-y-anna-r-costa-tendra-su-premiere-mundial-en-el-festival-internacional-de-cine-de-san-sebastian","status":"publish","type":"post","link":"https:\/\/ellascomunicacion.com\/en\/arde-madrid-la-serie-original-de-movistar-creada-por-paco-leon-y-anna-r-costa-tendra-su-premiere-mundial-en-el-festival-internacional-de-cine-de-san-sebastian\/","title":{"rendered":"\u201cArde Madrid\u201d, la serie original de Movistar+ creada por Paco Le\u00f3n y Anna R. Costa tendr\u00e1 su premiere mundial en el Festival Internacional de Cine de San Sebasti\u00e1n"},"content":{"rendered":"<p>Foto: Miguel Zaragoz\u00e1<\/p>\n<p><em>Arde Madrid<\/em>, la serie originial de Movistar+ creada por Paco Le\u00f3n y Anna R. Costa, se estrenar\u00e1 en el pr\u00f3ximo Festival Internacional de Cine de San Sebasti\u00e1n, que se desarrollar\u00e1 del 21 al 29 de septiembre.<\/p>\n<p>Esta innovadora ficci\u00f3n, protagonizada por Inma Cuesta, el propio Paco Le\u00f3n (que tambi\u00e9n dirige la serie), Debi Mazar, Anna Castillo y Juli\u00e1n Villagr\u00e1n, es la primera serie de la televisi\u00f3n de pago rodada en blanco y negro.<\/p>\n<p>Compuesta de 8 cap\u00edtulos de media hora cada uno, se proyectar\u00e1 completa en el Vel\u00f3dromo Antonio Elorza, la sala de cine m\u00e1s grande de Espa\u00f1a con una pantalla gigante de 400 metros cuadrados y un aforo para 3.000 espectadores.<\/p>\n<p><em>Arde Madrid<\/em> nos transporta a 1961, en plena dictadura franquista, donde Ava Gardner disfrutaba junto a una \u00e9lite de artistas, arist\u00f3cratas y extranjeros de lo que fue la Dolce Vita madrile\u00f1a. Su sufridor vecino de abajo, era nada m\u00e1s y nada menos que el General Per\u00f3n, exiliado de Argentina y reci\u00e9n casado con Isabelita, su segunda esposa. <\/p>\n<p>El General Per\u00f3n, Aline Griffith, Charlton Heston o la mism\u00edsima Ava Gardner ser\u00e1n secundarios de lujo en la vida de los verdaderos protagonistas de la serie: Manolo, Ana Mari y Pilar, el servicio dom\u00e9stico del animal m\u00e1s bello del mundo. <\/p>\n<p>A trav\u00e9s de sus vivencias se contar\u00e1 no s\u00f3lo la intimidad de una estrella de Hollywood sino tambi\u00e9n el disparate de lo que era la Espa\u00f1a del momento. Flamenco, guardias civiles, la Secci\u00f3n Femenina, clanes gitanos, un collar \u00fanico, espionaje \u2026 Y sobre todo sexo, whisky y rock and roll. <\/p>\n<p><em>Arde Madrid<\/em>, detr\u00e1s de cada momento hist\u00f3rico siempre hay alguien haciendo las camas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Miguel Zaragoz\u00e1 Arde Madrid, la serie originial de Movistar+ creada por Paco Le\u00f3n y Anna R. Costa, se estrenar\u00e1 en el pr\u00f3ximo Festival Internacional de Cine de San Sebasti\u00e1n, que se desarrollar\u00e1 del 21 al 29 de septiembre. Esta innovadora ficci\u00f3n, protagonizada por Inma Cuesta, el propio Paco Le\u00f3n (que tambi\u00e9n dirige la serie), Debi Mazar, Anna Castillo y Juli\u00e1n Villagr\u00e1n, es la primera serie de la televisi\u00f3n de pago rodada en blanco y negro. Compuesta de 8 cap\u00edtulos de media hora cada uno, se proyectar\u00e1 completa en el Vel\u00f3dromo Antonio Elorza, la sala de cine m\u00e1s grande de Espa\u00f1a con una pantalla gigante de 400 metros cuadrados y un aforo para 3.000 espectadores. Arde Madrid nos transporta a 1961, en plena dictadura franquista, donde Ava Gardner disfrutaba junto a una \u00e9lite de artistas, arist\u00f3cratas y extranjeros de lo que fue la Dolce Vita madrile\u00f1a. Su sufridor vecino de<\/p>\n","protected":false},"author":2,"featured_media":5845,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70,64],"tags":[],"class_list":["post-5847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-en","category-news"],"_links":{"self":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/comments?post=5847"}],"version-history":[{"count":1,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5847\/revisions"}],"predecessor-version":[{"id":5848,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5847\/revisions\/5848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media\/5845"}],"wp:attachment":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media?parent=5847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/categories?post=5847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/tags?post=5847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}