{"id":5837,"date":"2018-07-25T21:25:06","date_gmt":"2018-07-25T21:25:06","guid":{"rendered":"http:\/\/ellascomunicacion.com\/en\/la-noche-de-12-anos-de-alvaro-brechner-participara-en-el-festival-internacional-de-cine-de-venecia"},"modified":"2018-07-26T15:53:12","modified_gmt":"2018-07-26T15:53:12","slug":"la-noche-de-12-anos-de-alvaro-brechner-participara-en-el-festival-internacional-de-cine-de-venecia","status":"publish","type":"post","link":"https:\/\/ellascomunicacion.com\/en\/la-noche-de-12-anos-de-alvaro-brechner-participara-en-el-festival-internacional-de-cine-de-venecia\/","title":{"rendered":"\u201cLa noche de 12 a\u00f1os\u201d, de Alvaro Brechner, participar\u00e1 en el Festival Internacional de Cine de Venecia"},"content":{"rendered":"<p>Foto: Tornasol Films<\/p>\n<p>Madrid, 25 de julio de 2018 \u2013 El Festival Internacional de Cine de Venecia acoger\u00e1 en su edici\u00f3n n\u00famero 75 <em>La noche de 12 a\u00f1os<\/em>, escrita y dirigida por Alvaro Brechner, director hispano-uruguayo de reconocidos t\u00edtulos como \u201cMal d\u00eda para pescar\u201d (su primer largometraje que compiti\u00f3 en la secci\u00f3n oficial de la Semana de la Cr\u00edtica en Cannes) y \u201cKaplan\u201d.<\/p>\n<p><em>La noche de 12 a\u00f1os<\/em> competir\u00e1 en la Secci\u00f3n Horizontes de la pr\u00f3xima edici\u00f3n del certamen, que tendr\u00e1 lugar del 29 de agosto al 8 de septiembre.<\/p>\n<p>El filme, que llegar\u00e1 a los cines el 23 de noviembre distribuida por SYLDAVIA, est\u00e1 protagonizado por Antonio de la Torre (\u201cEl Autor\u201d, \u201cQue Dios nos perdone\u201d, \u201cTarde Para la ira\u201d), Chino Dar\u00edn (\u201cEl \u00c1ngel\u201d, \u201cLas leyes de la termodin\u00e1mica\u201d, \u201cLa Reina de Espa\u00f1a\u201d) y Alfonso Tort (\u201cLas Olas\u201d, \u201cCr\u00f3nica de una fuga\u201d, \u201cMal d\u00eda para pescar\u201d).<br \/>\nEl reparto lo completan Soledad Villamil (\u201cEl  Secreto de sus  ojos\u201d, \u201cTodos tenemos un Plan\u201d) y Silvia P\u00e9rez Cruz (\u201cCerca de tu casa\u201d).<\/p>\n<p> &#8220;<em>Es un gran honor y una gran alegr\u00eda haber sido seleccionado para presentar La Noche de 12 A\u00f1os en el Festival Internacional de Venecia. Es una pel\u00edcula que habla sobre nuestro mundo, nuestras esperanzas y pesadillas, y me cuesta imaginarme un lugar ideal, m\u00e1s maravilloso y m\u00e1gico que el Festival de Venecia. Despu\u00e9s de tantos a\u00f1os de trabajo es casi un sue\u00f1o que vaya ahora a ser vista por tanta gente en el festival m\u00e1s antiguo del mundo, fiel testimonio del amor al cine que por sus pantallas pasa<\/em>\u201d. Alvaro Brechner<\/p>\n<p>Inspirada en la historia real de Jos\u00e9 Mujica, Mauricio Rosencof y Eleuterio Fern\u00e1ndez Huidobro, <em>La noche de 12 a\u00f1os<\/em>, es una historia de superaci\u00f3n y resistencia, pero, sobre todo, es la historia de la lucha existencial de tres hombres que en sus horas m\u00e1s oscuras, se aferraron a su esp\u00edritu para mantener su humanidad y esperanza. Estos tres hombres son:<\/p>\n<p>\u2022 Jos\u00e9 Mujica, interpretado por Antonio de la Torre, fue elegido diputado y senador, en 2010 y, a sus 75 a\u00f1os, se convirti\u00f3 en el presidente electo por mayor\u00eda democr\u00e1tica en Uruguay. <\/p>\n<p>\u2022 Mauricio Rosencof, interpretado por Chino Dar\u00edn, novelista, poeta, periodista y ex Director de Cultura de la Intendencia de Montevideo.<\/p>\n<p>\u2022 Eleuterio Fern\u00e1ndez Huidobro, interpretado por Alfonso Tort, fue elegido senador, y posteriormente asumi\u00f3 en 2011 el cargo de Ministro de Defensa de Uruguay. Falleci\u00f3 en agosto de 2016.<\/p>\n<p>Producida por TORNASOL FILMS y ALCARAVAN AIE (Espa\u00f1a) en coproducci\u00f3n con HADDOCK FILMS-ALEPH MEDIA (Argentina) MANNY FILMS (Francia) y SALADO (Uruguay), con la participaci\u00f3n de MOVISTAR+, NETFLIX y ZDF\/ARTE, y el apoyo del ICAA, INCAA, CNC, L\u00b4AIDE AUX CINEMAS DU MONDE, INSTITUT FRAN\u00c7AIS, IBERMEDIA y EURIMAGES, la pel\u00edcula ser\u00e1 distribuida en Espa\u00f1a por SYLDAVIA.<\/p>\n<p>La compa\u00f1\u00eda LATIDO FILMS es la responsable de las ventas internacionales.<\/p>\n<p>Sinopsis<br \/>\nTres hombres son sometidos a un secreto experimento a trav\u00e9s del cual la dictadura militar quiere volverlos locos. Arrojados a diminutos calabozos, no pueden hablar, apenas ver, comer o dormir. Empujados sus cuerpos y mentes m\u00e1s all\u00e1 de los l\u00edmites de lo imaginable, los rehenes libraron una batalla existencial para escapar a la terrible realidad que los condenaba a la locura. La pel\u00edcula est\u00e1 basada en los 12 a\u00f1os de confinamiento solitario que vivieron tres de las personalidades m\u00e1s reconocidas del Uruguay contempor\u00e1neo, entre ellos su ex presidente, Jos\u00e9 \u201cPepe\u201d Mujica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Tornasol Films Madrid, 25 de julio de 2018 \u2013 El Festival Internacional de Cine de Venecia acoger\u00e1 en su edici\u00f3n n\u00famero 75 La noche de 12 a\u00f1os, escrita y dirigida por Alvaro Brechner, director hispano-uruguayo de reconocidos t\u00edtulos como \u201cMal d\u00eda para pescar\u201d (su primer largometraje que compiti\u00f3 en la secci\u00f3n oficial de la Semana de la Cr\u00edtica en Cannes) y \u201cKaplan\u201d. La noche de 12 a\u00f1os competir\u00e1 en la Secci\u00f3n Horizontes de la pr\u00f3xima edici\u00f3n del certamen, que tendr\u00e1 lugar del 29 de agosto al 8 de septiembre. El filme, que llegar\u00e1 a los cines el 23 de noviembre distribuida por SYLDAVIA, est\u00e1 protagonizado por Antonio de la Torre (\u201cEl Autor\u201d, \u201cQue Dios nos perdone\u201d, \u201cTarde Para la ira\u201d), Chino Dar\u00edn (\u201cEl \u00c1ngel\u201d, \u201cLas leyes de la termodin\u00e1mica\u201d, \u201cLa Reina de Espa\u00f1a\u201d) y Alfonso Tort (\u201cLas Olas\u201d, \u201cCr\u00f3nica de una fuga\u201d, \u201cMal d\u00eda para pescar\u201d). El reparto lo<\/p>\n","protected":false},"author":2,"featured_media":5834,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[70,64],"tags":[],"class_list":["post-5837","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-blog-en","category-news","post_format-post-format-video"],"_links":{"self":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/comments?post=5837"}],"version-history":[{"count":1,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5837\/revisions"}],"predecessor-version":[{"id":5838,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5837\/revisions\/5838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media\/5834"}],"wp:attachment":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media?parent=5837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/categories?post=5837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/tags?post=5837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}