{"id":5415,"date":"2017-04-27T10:25:28","date_gmt":"2017-04-27T10:25:28","guid":{"rendered":"http:\/\/ellascomunicacion.com\/en\/victor-ullate-inaugura-la-jornada-del-dia-internacional-de-la-danza-con-la-lectura-del-manifiesto-de-la-unesco"},"modified":"2017-04-27T10:26:35","modified_gmt":"2017-04-27T10:26:35","slug":"victor-ullate-inaugura-la-jornada-del-dia-internacional-de-la-danza-con-la-lectura-del-manifiesto-de-la-unesco","status":"publish","type":"post","link":"https:\/\/ellascomunicacion.com\/en\/victor-ullate-inaugura-la-jornada-del-dia-internacional-de-la-danza-con-la-lectura-del-manifiesto-de-la-unesco\/","title":{"rendered":"V\u00edctor Ullate inaugura la jornada del D\u00eda Internacional de la Danza con la lectura del Manifiesto de la UNESCO"},"content":{"rendered":"<p>\u00a9 Fernando Marcos<\/p>\n<p>El s\u00e1bado 29 de abril se celebra el D\u00eda Internacional de la Danza en Teatros del Canal, la jornada empezar\u00e1 con la lectura del Manifiesto de la UNESCO a cargo del Maestro Ullate. A continuaci\u00f3n, los dos bailarines principales del V\u00edctor Ullate Ballet, Marlen Fuerte y Josu\u00e9 Ullate, interpretar\u00e1n un paso a dos in\u00e9dito de Carmen, la nueva producci\u00f3n de la Compa\u00f1\u00eda en la que el maestro Ullate trabaja con pasi\u00f3n durante los \u00faltimos meses y que se estrenar\u00e1 el 31 de agosto en Teatros del Canal de Madrid. Tras esta actuaci\u00f3n, tendr\u00e1 lugar una clase abierta al p\u00fablico para dar a conocer c\u00f3mo trabaja una compa\u00f1\u00eda de ballet cl\u00e1sico.<\/p>\n<p>Uni\u00e9ndose a las celebraciones del D\u00eda Internacional de la Danza, tambi\u00e9n desde la Escuela V\u00edctor Ullate se llevar\u00e1n a cabo m\u00faltiples actividades. Durante toda la semana la escuela mantendr\u00e1 sus puertas abiertas, para invitar a probar sus clases a todo el que lo desee; y un a\u00f1o m\u00e1s, volver\u00e1 a llevar la Danza a la calle en un evento abierto al p\u00fablico en el que participan alumnos y profesores. Una forma diferente de tomar el espacio urbano y celebrar la Danza que permita una interacci\u00f3n con el lugar y con los vecinos del barrio. <\/p>\n<p>Ser\u00e1 ma\u00f1ana viernes 28 de abril desde las 18h30, en la terraza de Casa de Vacas del Retiro. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a9 Fernando Marcos El s\u00e1bado 29 de abril se celebra el D\u00eda Internacional de la Danza en Teatros del Canal, la jornada empezar\u00e1 con la lectura del Manifiesto de la UNESCO a cargo del Maestro Ullate. A continuaci\u00f3n, los dos bailarines principales del V\u00edctor Ullate Ballet, Marlen Fuerte y Josu\u00e9 Ullate, interpretar\u00e1n un paso a dos in\u00e9dito de Carmen, la nueva producci\u00f3n de la Compa\u00f1\u00eda en la que el maestro Ullate trabaja con pasi\u00f3n durante los \u00faltimos meses y que se estrenar\u00e1 el 31 de agosto en Teatros del Canal de Madrid. Tras esta actuaci\u00f3n, tendr\u00e1 lugar una clase abierta al p\u00fablico para dar a conocer c\u00f3mo trabaja una compa\u00f1\u00eda de ballet cl\u00e1sico. Uni\u00e9ndose a las celebraciones del D\u00eda Internacional de la Danza, tambi\u00e9n desde la Escuela V\u00edctor Ullate se llevar\u00e1n a cabo m\u00faltiples actividades. Durante toda la semana la escuela mantendr\u00e1 sus puertas abiertas, para invitar a probar sus<\/p>\n","protected":false},"author":2,"featured_media":5413,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[],"class_list":["post-5415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/comments?post=5415"}],"version-history":[{"count":1,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5415\/revisions"}],"predecessor-version":[{"id":5416,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5415\/revisions\/5416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media\/5413"}],"wp:attachment":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media?parent=5415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/categories?post=5415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/tags?post=5415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}