{"id":5050,"date":"2016-07-27T13:16:39","date_gmt":"2016-07-27T13:16:39","guid":{"rendered":"http:\/\/ellascomunicacion.com\/en\/trailer-de-ozzy"},"modified":"2016-09-08T19:01:37","modified_gmt":"2016-09-08T19:01:37","slug":"trailer-de-ozzy","status":"publish","type":"post","link":"https:\/\/ellascomunicacion.com\/en\/trailer-de-ozzy\/","title":{"rendered":"Trailer de &#8220;Ozzy&#8221;"},"content":{"rendered":"<p>Ya est\u00e1 disponible el primer tr\u00e1iler de la pel\u00edcula espa\u00f1ola de animaci\u00f3n <em>Ozzy<\/em>.<br \/>\n<em>Ozzy<\/em>, una producci\u00f3n de Capit\u00e1n Ara\u00f1a, Arcadia Motion Pictures, Pachacamac Films y Tangent Animation en colaboraci\u00f3n con Atresmedia Cine, est\u00e1 dirigida por Alberto Rodr\u00edguez (&#8220;Pocoy\u00f3&#8221;), y codirigida por Nacho La Casa.<\/p>\n<p>Buena Vista Internacional estrenar\u00e1 este largometraje en cines el pr\u00f3ximo 14 de octubre. La producci\u00f3n ejecutiva corre a cargo de Nacho La Casa, Ibon Cormenzana e Ignasi Estap\u00e9 y cuenta en el cast de voces con la participaci\u00f3n de Dani Rovira, Jos\u00e9 Mota, Michelle Jenner, Fernando Tejero, Carlos Areces, Elsa Pataky, Pablo Espinosa, Selu Nieto y la colaboraci\u00f3n especial de Manolo Lama, Maldini y Mat\u00edas Prats.<\/p>\n<p>La id\u00edlica vida de Ozzy, un simp\u00e1tico y pac\u00edfico beagle que se ha criado entre algodones junto a la familia Martin, va a dar un vuelco. Cuando su familia no puede llevarle a un largo viaje lejos de su hogar, le depositan en lo que creen que es el mejor balneario canino, Blue Creek. Pero la perfecta estampa del lugar resulta ser una fachada urdida por su villano propietario, y otro destino bien distinto aguarda a Ozzy: \u00e9ste ir\u00e1 pronto a parar al verdadero Blue Creek, una c\u00e1rcel para perros, habitada en su mayor\u00eda por duros chuchos callejeros y donde prevalece la ley del m\u00e1s fuerte. All\u00ed dentro Ozzy tendr\u00e1 que esquivar el peligro, encontrar fuerzas donde no cre\u00eda tenerlas y aprender a apoyarse en Chester, Fronky y Doc, los nuevos amigos que le acompa\u00f1ar\u00e1n en esta aventura para intentar regresar sano y salvo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya est\u00e1 disponible el primer tr\u00e1iler de la pel\u00edcula espa\u00f1ola de animaci\u00f3n Ozzy. Ozzy, una producci\u00f3n de Capit\u00e1n Ara\u00f1a, Arcadia Motion Pictures, Pachacamac Films y Tangent Animation en colaboraci\u00f3n con Atresmedia Cine, est\u00e1 dirigida por Alberto Rodr\u00edguez (&#8220;Pocoy\u00f3&#8221;), y codirigida por Nacho La Casa. Buena Vista Internacional estrenar\u00e1 este largometraje en cines el pr\u00f3ximo 14 de octubre. La producci\u00f3n ejecutiva corre a cargo de Nacho La Casa, Ibon Cormenzana e Ignasi Estap\u00e9 y cuenta en el cast de voces con la participaci\u00f3n de Dani Rovira, Jos\u00e9 Mota, Michelle Jenner, Fernando Tejero, Carlos Areces, Elsa Pataky, Pablo Espinosa, Selu Nieto y la colaboraci\u00f3n especial de Manolo Lama, Maldini y Mat\u00edas Prats. La id\u00edlica vida de Ozzy, un simp\u00e1tico y pac\u00edfico beagle que se ha criado entre algodones junto a la familia Martin, va a dar un vuelco. Cuando su familia no puede llevarle a un largo viaje lejos de su hogar,<\/p>\n","protected":false},"author":2,"featured_media":5149,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[70,64],"tags":[],"class_list":["post-5050","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-blog-en","category-news","post_format-post-format-video"],"_links":{"self":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/comments?post=5050"}],"version-history":[{"count":1,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5050\/revisions"}],"predecessor-version":[{"id":5051,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/5050\/revisions\/5051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media\/5149"}],"wp:attachment":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media?parent=5050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/categories?post=5050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/tags?post=5050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}