{"id":10508,"date":"2025-07-21T15:35:20","date_gmt":"2025-07-21T15:35:20","guid":{"rendered":"https:\/\/ellascomunicacion.com\/tres-adioses-de-isabel-coixet-tendra-su-estreno-mundial-en-el-festival-internacional-de-cine-de-toronto"},"modified":"2025-07-21T15:35:53","modified_gmt":"2025-07-21T15:35:53","slug":"tres-adioses-de-isabel-coixet-tendra-su-estreno-mundial-en-el-festival-internacional-de-cine-de-toronto","status":"publish","type":"post","link":"https:\/\/ellascomunicacion.com\/en\/tres-adioses-de-isabel-coixet-tendra-su-estreno-mundial-en-el-festival-internacional-de-cine-de-toronto\/","title":{"rendered":"&#8220;Tres adioses&#8221; de Isabel Coixet tendr\u00e1 su estreno mundial en el Festival Internacional de Cine de Toronto"},"content":{"rendered":"<p>Foto: \u00a9 Greta de Lazzaris<\/p>\n<p>Madrid, 21 de julio de 2025 \u2013 <strong>\u201cTRES ADIOSES\u201d<\/strong>, la nueva pel\u00edcula de <strong>Isabel Coixet<\/strong>, se estrenar\u00e1 en la secci\u00f3n \u201cSpecial Presentations\u201d del prestigioso Festival Internacional de Cine de Toronto (TIFF), que tendr\u00e1 lugar del 4 al 14 de septiembre.<\/p>\n<p>Basada en \u201cTre ciotole\u201d, el libro p\u00f3stumo y semi autobiogr\u00e1fico de Michela Murgia -activista feminista y una de las intelectuales m\u00e1s influyentes de Italia-,  la pel\u00edcula est\u00e1 escrita por la propia Coixet junto al guionista Enrico Audenino.<\/p>\n<p>Tras lo que parec\u00eda una discusi\u00f3n sin importancia, Marta (Alba Rohrwacher) y Antonio (Elio Germano) se separan. \u00c9l, un chef prometedor, se refugia en sus fogones; ella, en su silencio, empieza a notar algo m\u00e1s que tristeza: ha perdido el apetito\u2026 y no solo por desamor. Cuando descubre que detr\u00e1s hay un problema de salud, todo da un giro inesperado: la comida sabe mejor, la m\u00fasica le llega como nunca y el deseo despierta sus ganas de vivir sin miedo.<br \/>\nUna historia sobre el amor, la vida y esos momentos que lo cambian todo para siempre.<\/p>\n<p><strong>\u201cTRES ADIOSES\u201d <\/strong>es una coproducci\u00f3n italo-espa\u00f1ola protagonizada por <strong>Alba Rohrwacher, Elio Germano, Francesco Carril, Silvia D\u2019Amico, Galatea Bellugi y por Sarita Choudhury<\/strong>.<\/p>\n<p>Alba Rohrwacher, una de las actrices m\u00e1s reconocidas del cine italiano contempor\u00e1neo, da vida a Marta. Ganadora de la Copa Volpi a la mejor actriz del Festival de Venecia por \u201cHungry Hearts\u201d, tambi\u00e9n ha estado nominada cinco veces al David di Donatello, y  cuenta en su filmograf\u00eda con t\u00edtulos como \u201cLa quimera\u201d y \u201cLazzaro feliz\u201d, dirigidos por su hermana Alicia Rohrwacher, \u201cLa soledad de los n\u00fameros primos\u201d de Saverio Costanzo, o la serie \u201cla amiga estupenda\u201d.<\/p>\n<p>Elio Germano, en el papel de Antonio, es uno de los actores italianos m\u00e1s premiados de su generaci\u00f3n, con galardones como el Premio al Mejor Actor en el Festival de Cannes por \u201cLa nostra vita\u201d, Daniele Luchetti, o  el Oso de Plata en la Berlinale y el David di Donatello por \u201cVolevo nascondermi\u201d, de Giorgio Diritti.<\/p>\n<p>Por su parte, Francesco Carril, que ya trabaj\u00f3 con Coixet en \u201cUn amor\u201d, ha sido reconocido por su papel en la serie \u201cLos a\u00f1os nuevos\u201d de Rodrigo Sorogoyen y por sus colaboraciones con Jon\u00e1s Trueba en t\u00edtulos como \u201cTen\u00e9is que venir a verla\u201d, \u201cLa virgen de agosto\u201d y \u201cLos ilusos\u201d.<\/p>\n<p>Isabel Coixet, que cuenta en su filmograf\u00eda con t\u00edtulos como \u201cLa librer\u00eda\u201d, \u201cLa vida secreta de las palabras\u201d, \u201cMi vida sin m\u00ed\u201d o \u201cUn amor\u201d, es la directora que cuenta con m\u00e1s premios Goya, incluidos dos a la Mejor Pel\u00edcula y varios a la Mejor Direcci\u00f3n y Gui\u00f3n. Entre otros reconocimientos, ha recibido el Premio Nacional de Cinematograf\u00eda, la Medalla Chevalier des Arts et des Lettres del Ministerio de Cultura franc\u00e9s y el European Achievement in World Cinema Award.<\/p>\n<p><strong>\u201cTRES ADIOSES\u201d<\/strong>, que llegar\u00e1 a los cines de Espa\u00f1a en 2026 de la mano de Bteam Pictures, supone una nueva colaboraci\u00f3n de Coixet con las productoras espa\u00f1olas de \u201cUn amor\u201d, su anterior film.<br \/>\nLa pel\u00edcula es una producci\u00f3n italo-espa\u00f1ola de Cattleya (parte de ITV Studios), Ruvido Produzioni, Bartlebyfilm, Buenapinta Media, Bteam Prods, Perdici\u00f3n Films, Apaches Entertainment y Tres Cuencos AIE. Cuenta con el apoyo del Ministerio de Cultura italiano (MIC \u2013 DGCA) y la participaci\u00f3n de Sky, RTVE y MAX.<br \/>\nLa distribuci\u00f3n internacional est\u00e1 a cargo de Vision Distribution.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: \u00a9 Greta de Lazzaris Madrid, 21 de julio de 2025 \u2013 \u201cTRES ADIOSES\u201d, la nueva pel\u00edcula de Isabel Coixet, se estrenar\u00e1 en la secci\u00f3n \u201cSpecial Presentations\u201d del prestigioso Festival Internacional de Cine de Toronto (TIFF), que tendr\u00e1 lugar del 4 al 14 de septiembre. Basada en \u201cTre ciotole\u201d, el libro p\u00f3stumo y semi autobiogr\u00e1fico de Michela Murgia -activista feminista y una de las intelectuales m\u00e1s influyentes de Italia-, la pel\u00edcula est\u00e1 escrita por la propia Coixet junto al guionista Enrico Audenino. Tras lo que parec\u00eda una discusi\u00f3n sin importancia, Marta (Alba Rohrwacher) y Antonio (Elio Germano) se separan. \u00c9l, un chef prometedor, se refugia en sus fogones; ella, en su silencio, empieza a notar algo m\u00e1s que tristeza: ha perdido el apetito\u2026 y no solo por desamor. Cuando descubre que detr\u00e1s hay un problema de salud, todo da un giro inesperado: la comida sabe mejor, la m\u00fasica le llega<\/p>\n","protected":false},"author":2,"featured_media":10506,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70,64],"tags":[],"class_list":["post-10508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-en","category-news"],"_links":{"self":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/10508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/comments?post=10508"}],"version-history":[{"count":1,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/10508\/revisions"}],"predecessor-version":[{"id":10509,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/10508\/revisions\/10509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media\/10506"}],"wp:attachment":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media?parent=10508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/categories?post=10508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/tags?post=10508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}