{"id":10478,"date":"2025-06-01T10:43:07","date_gmt":"2025-06-01T10:43:07","guid":{"rendered":"https:\/\/ellascomunicacion.com\/flores-para-antonio-se-estrenara-en-cines-el-10-de-octubre"},"modified":"2025-06-27T10:47:50","modified_gmt":"2025-06-27T10:47:50","slug":"flores-para-antonio-se-estrenara-en-cines-el-10-de-octubre","status":"publish","type":"post","link":"https:\/\/ellascomunicacion.com\/en\/flores-para-antonio-se-estrenara-en-cines-el-10-de-octubre\/","title":{"rendered":"&#8220;Flores para Antonio&#8221; se estrenar\u00e1 en cines el 10 de octubre"},"content":{"rendered":"<p><strong>Flores para Antonio<\/strong>, la pel\u00edcula documental que recorre la vida y la obra del m\u00fasico y compositor Antonio Flores de la mano de su hija, la actriz Alba Flores, se estrenar\u00e1 en cines el 10 de octubre.<\/p>\n<p>Se cumplen 30 a\u00f1os del fallecimiento de Antonio Flores (30 de mayo de 1995) y, coincidiendo con el aniversario, este largometraje documental escrito y dirigido por  Elena Molina (&#8216;Remember my name&#8217;) e Isaki Lacuesta (premio Goya al mejor director por &#8216;Segundo premio&#8217;, &#8216;Un a\u00f1o, una noche&#8217;) propone un viaje \u00edntimo para acercarnos a la memoria y la vida del m\u00fasico, uno de los artistas que m\u00e1s han trascendido y calado en la m\u00fasica de este pa\u00eds, y cuyo legado contin\u00faa muy presente. <\/p>\n<p>A trav\u00e9s de materiales in\u00e9ditos, como v\u00eddeos caseros, fotos, dibujos, im\u00e1genes de  archivo y su propia m\u00fasica, el espectador acompa\u00f1ar\u00e1 a su hija Alba en su b\u00fasqueda de respuestas, ahondando en la figura del m\u00fasico y compositor.<\/p>\n<p>Alba Flores (\u2018La casa de papel\u2019, \u2018Vis a vis\u2019) desvela nuevas facetas sobre la vida y la obra del artista junto a su familia (como con su madre, Ana Villa, o sus t\u00edas, las c\u00e9lebres Lolita y Rosario Flores), y reconocidos artistas como Antonio Carmona, Ariel Rot, Joaqu\u00edn Sabina o S\u00edlvia P\u00e9rez Cruz, entre otros.<\/p>\n<p><strong>Flores para Antonio <\/strong>es un largometraje documental original Movistar Plus+ producido por Flower Power Producciones, LACOproductora, Caballo Films, Flores para Antonio la pel\u00edcula AIE, y  con la financiaci\u00f3n del ICAA y la Comunidad de Madrid. <\/p>\n<p>La pel\u00edcula, que se ha rodado en localizaciones de Madrid y la provincia de C\u00e1diz (Jerez de la Frontera, entre otras localidades) se estrenar\u00e1 en salas de cine el 10 de octubre distribuida por A Contracorriente Films y, posteriormente, llegar\u00e1 en exclusiva a Movistar Plus+. <\/p>\n<p>Las ventas internacionales corren a cargo de Goodfellas.<\/p>\n<p>SINOPSIS<br \/>\nUna hija se dispone a averiguar la verdad sobre qui\u00e9n fue su padre, un m\u00fasico legendario, fallecido cuando ella ten\u00eda 8 a\u00f1os. \u00c9l es Antonio Flores, ella la tambi\u00e9n c\u00e9lebre actriz Alba Flores. Alba dej\u00f3 de cantar al perder a Antonio y ahora se dispone a recuperar su voz y su historia, interrogando por primera vez a sus familiares y amistades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Flores para Antonio, la pel\u00edcula documental que recorre la vida y la obra del m\u00fasico y compositor Antonio Flores de la mano de su hija, la actriz Alba Flores, se estrenar\u00e1 en cines el 10 de octubre. Se cumplen 30 a\u00f1os del fallecimiento de Antonio Flores (30 de mayo de 1995) y, coincidiendo con el aniversario, este largometraje documental escrito y dirigido por Elena Molina (&#8216;Remember my name&#8217;) e Isaki Lacuesta (premio Goya al mejor director por &#8216;Segundo premio&#8217;, &#8216;Un a\u00f1o, una noche&#8217;) propone un viaje \u00edntimo para acercarnos a la memoria y la vida del m\u00fasico, uno de los artistas que m\u00e1s han trascendido y calado en la m\u00fasica de este pa\u00eds, y cuyo legado contin\u00faa muy presente. A trav\u00e9s de materiales in\u00e9ditos, como v\u00eddeos caseros, fotos, dibujos, im\u00e1genes de archivo y su propia m\u00fasica, el espectador acompa\u00f1ar\u00e1 a su hija Alba en su b\u00fasqueda de respuestas, ahondando en<\/p>\n","protected":false},"author":2,"featured_media":10476,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70,64],"tags":[],"class_list":["post-10478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-en","category-news"],"_links":{"self":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/10478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/comments?post=10478"}],"version-history":[{"count":1,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/10478\/revisions"}],"predecessor-version":[{"id":10479,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/10478\/revisions\/10479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media\/10476"}],"wp:attachment":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media?parent=10478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/categories?post=10478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/tags?post=10478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}