{"id":10397,"date":"2025-03-11T10:18:05","date_gmt":"2025-03-11T10:18:05","guid":{"rendered":"https:\/\/ellascomunicacion.com\/arranca-el-rodaje-de-golpes-de-rafael-cobos-con-luis-tosar-jesus-carroza-y-teresa-garzon"},"modified":"2025-03-11T10:18:40","modified_gmt":"2025-03-11T10:18:40","slug":"arranca-el-rodaje-de-golpes-de-rafael-cobos-con-luis-tosar-jesus-carroza-y-teresa-garzon","status":"publish","type":"post","link":"https:\/\/ellascomunicacion.com\/en\/arranca-el-rodaje-de-golpes-de-rafael-cobos-con-luis-tosar-jesus-carroza-y-teresa-garzon\/","title":{"rendered":"Arranca el rodaje de \u201cGolpes\u201d, de Rafael Cobos, con Luis Tosar, Jes\u00fas Carroza y Teresa Garz\u00f3n"},"content":{"rendered":"<p>Foto: \u00a9\ufe0f Julio Vergne<\/p>\n<p>11 de marzo de 2025. <strong>\u2018GOLPES\u2019<\/strong>, dirigida por <strong>Rafael Cobos<\/strong> y protagonizada por <strong>Luis Tosar<\/strong>, <strong>Jes\u00fas Carroza<\/strong> y <strong>Teresa Garz\u00f3n<\/strong>, comienza su rodaje, que se prolongar\u00e1 a lo largo de siete semanas en diferentes localizaciones de Sevilla y Madrid.<\/p>\n<p>Rafael Cobos, que debut\u00f3 en la direcci\u00f3n con la serie \u2018El hijo zurdo\u2019 (premiada en Canneseries), tiene una larga y s\u00f3lida trayectoria como guionista, estrechamente vinculada al director Alberto Rodr\u00edguez, juntos han creado historias que combinan profundidad narrativa con un agudo sentido de la realidad social y cultural de nuestro pa\u00eds, como \u2018Grupo 7\u2019 \u2018La isla m\u00ednima\u2019 y \u2018El hombre de las mil caras\u2019 y \u2018Modelo 77\u2019; su fruct\u00edfera colaboraci\u00f3n ha sido reconocida con dos premios Goya y hasta cuatro nominaciones.  Adem\u00e1s, en televisi\u00f3n destacan sus trabajos como guionista en \u2018Apag\u00f3n\u2019 y como cocreador y showrunner de \u2018La peste\u2019.<\/p>\n<p>En esta ocasi\u00f3n, Cobos se pone tras la c\u00e1mara, en el que es su primer largometraje como director; una historia que adem\u00e1s coescribe junto al guionista <strong>Fernando Navarro<\/strong> (\u2018Segundo Premio\u2019, \u2018Or\u00edgenes secretos\u2019 \u2018Ver\u00f3nica\u2019), nominado en dos ocasiones a los premios Goya.<\/p>\n<p>Protagonizada por el ganador de tres premios Goya, Luis Tosar (\u2018La Infiltrada\u2019, \u2018Celda 211\u2019, \u2018Te doy mis ojos\u2019, \u2018Los lunes al sol\u2019), Jes\u00fas Carroza (\u2018Modelo 77\u2019, \u2018La isla m\u00ednima\u2019), premio Goya a Mejor actor revelaci\u00f3n, y Teresa Garz\u00f3n (\u2018Noches de Tef\u00eda\u2019), \u2018GOLPES\u2019 es una nueva mirada al cine quinqui, un subg\u00e9nero cinematogr\u00e1fico que surge en los a\u00f1os 80; un thriller vertiginoso, pero con una visi\u00f3n compleja, que se alimenta de la leyenda y del relato de sus personajes. Completan el reparto <strong>Cristina Alc\u00e1zar<\/strong>, <strong>Carlos Bernardino<\/strong> y <strong>Cristalino<\/strong>.<\/p>\n<p><strong>En palabras de Rafael Cobos:<\/strong> \u2018<em>Golpes<\/em>\u2019 <em>es una apuesta por revitalizar el cine quinqui, ahondar en su esencia, pero buscando la diferencia. Si el cine quinqui es frontal, expli\u0301cito y habla de las cosas de un modo evidente y descarnado, \u2018Golpes\u2019 es una fa\u0301bula sutil que pretende hablar de un pa\u00eds en plena transicio\u0301n, contradictorio, desorientado e incapaz de ajustar cuentas con su pasado. Un thriller sobre los lazos de sangre y la memoria<\/em>\u2019.<\/p>\n<p>En el equipo t\u00e9cnico destacan los nombres de <strong>Sergi Vilanova Claud\u00edn<\/strong> (\u2018Saben aquell\u2019, \u2018Ad\u00fa\u2019), en la direcci\u00f3n de fotograf\u00eda; <strong>Gigia Pellegrini<\/strong> (\u2018Segundo premio\u2019, \u2018Modelo 77\u2019) en la direcci\u00f3n de Arte; <strong>Tamara Soto<\/strong> (\u2018El caso Asunta\u2019, \u2018El cuerpo abierto\u2019) en la direcci\u00f3n de producci\u00f3n; <strong>Lourdes Fuentes<\/strong> (\u2018Segundo premio\u2019, \u2018La trinchera infinita\u2019), como jefa de Vestuario; <strong>Yolanda Pi\u00f1a<\/strong> (\u2018Modelo 77 \u2019, \u2018La trinchera infinita\u2019), en maquillaje y peluquer\u00eda, y <strong>Carlos Mouri\u00f1o<\/strong> (\u2018Clanes\u2019, \u2018Honeymoon\u2019) como jefe de sonido. De la m\u00fasica original estar\u00e1 a cargo el artista musical <strong>Bronquio<\/strong>.<\/p>\n<p><strong>\u2018GOLPES\u2019<\/strong> es un producci\u00f3n de <strong>Borja Pena<\/strong> y <strong>Emma Lustres<\/strong> para <em>VACA FILMS<\/em> en coproducci\u00f3n con <strong>Grupo Tranquilo<\/strong> y <strong>Playtime<\/strong> (Francia), con la participaci\u00f3n de <strong>Movistar Plus+<\/strong>, <strong>RTVE<\/strong> y <strong>Canal Sur<\/strong>, con la financiaci\u00f3n de <strong>ICAA<\/strong>&#8211;<strong>Ministerio de Cultura<\/strong> y la <strong>Administraci\u00f3n de la Junta de Andaluc\u00eda \u2013 Consejer\u00eda de Cultura y Deporte<\/strong> y el apoyo de <strong>Programa Europa Creativa de la Uni\u00f3n Europea<\/strong>.<\/p>\n<p><strong>A Contracorriente Films<\/strong> estar\u00e1 a cargo de la distribuci\u00f3n.<\/p>\n<p>SINOPSIS<\/p>\n<p>\u2018GOLPES\u2019 narra la historia de Migueli, un delincuente que sale de prisi\u00f3n en la cambiante Espa\u00f1a de inicios de los 80. Quiere mirar al futuro, pero, antes, tendr\u00e1 que sellar heridas del pasado. Para ello necesita mucho dinero y lo necesita r\u00e1pido. En cuanto llega a Sevilla re\u00fane a su antigua banda, y dan varios palos seguidos: sucursales bancarias, joyer\u00edas\u2026 e incluso el primer casino de la zona. No van a tenerlo f\u00e1cil: la polic\u00eda ha encargado el caso a su propio hermano, Sabino, que conoce muy bien c\u00f3mo piensan. Pero Migueli no se detendr\u00e1. Est\u00e1 dispuesto a llegar hasta el final.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: \u00a9\ufe0f Julio Vergne 11 de marzo de 2025. \u2018GOLPES\u2019, dirigida por Rafael Cobos y protagonizada por Luis Tosar, Jes\u00fas Carroza y Teresa Garz\u00f3n, comienza su rodaje, que se prolongar\u00e1 a lo largo de siete semanas en diferentes localizaciones de Sevilla y Madrid. Rafael Cobos, que debut\u00f3 en la direcci\u00f3n con la serie \u2018El hijo zurdo\u2019 (premiada en Canneseries), tiene una larga y s\u00f3lida trayectoria como guionista, estrechamente vinculada al director Alberto Rodr\u00edguez, juntos han creado historias que combinan profundidad narrativa con un agudo sentido de la realidad social y cultural de nuestro pa\u00eds, como \u2018Grupo 7\u2019 \u2018La isla m\u00ednima\u2019 y \u2018El hombre de las mil caras\u2019 y \u2018Modelo 77\u2019; su fruct\u00edfera colaboraci\u00f3n ha sido reconocida con dos premios Goya y hasta cuatro nominaciones. Adem\u00e1s, en televisi\u00f3n destacan sus trabajos como guionista en \u2018Apag\u00f3n\u2019 y como cocreador y showrunner de \u2018La peste\u2019. En esta ocasi\u00f3n, Cobos se pone tras la<\/p>\n","protected":false},"author":2,"featured_media":10395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70,64,57],"tags":[],"class_list":["post-10397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-en","category-news","category-sin-categoria-en"],"_links":{"self":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/10397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/comments?post=10397"}],"version-history":[{"count":1,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/10397\/revisions"}],"predecessor-version":[{"id":10398,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/posts\/10397\/revisions\/10398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media\/10395"}],"wp:attachment":[{"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/media?parent=10397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/categories?post=10397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellascomunicacion.com\/en\/wp-json\/wp\/v2\/tags?post=10397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}